{"id":63890,"date":"2026-04-15T05:00:00","date_gmt":"2026-04-15T10:00:00","guid":{"rendered":"https:\/\/latamobility.com\/?p=63890"},"modified":"2026-04-13T10:56:19","modified_gmt":"2026-04-13T15:56:19","slug":"chevrolet-toyota-veiculos-eletricos-colombia-marco-2026","status":"publish","type":"post","link":"https:\/\/latamobility.com\/pt-br\/chevrolet-toyota-veiculos-eletricos-colombia-marco-2026\/","title":{"rendered":"General Motors e Toyota registram crescimento hist\u00f3rico em ve\u00edculos el\u00e9tricos na Col\u00f4mbia"},"content":{"rendered":"\n<p>O mercado de ve\u00edculos el\u00e9tricos na <strong>Col\u00f4mbia <\/strong>viveu um <strong>mar\u00e7o hist\u00f3rico<\/strong>, com <strong>crescimento de 267%<\/strong> impulsionado pela entrada da Tesla no mercado local.<\/p>\n\n\n\n<p>De acordo com o <strong><a href=\"https:\/\/www.fenalco.com.co\/blog\/gremial-4\/informe-del-sector-automotor-a-marzo-2026-8751\">relat\u00f3rio<\/a><\/strong> mais recente da <strong>Associa\u00e7\u00e3o Nacional de Mobilidade Sustent\u00e1vel<\/strong> (Andemos), foram matriculados <strong>5.083 ve\u00edculos de emiss\u00e3o zero<\/strong> durante o terceiro m\u00eas do ano \u2014 um n\u00famero que mostra o ritmo acelerado de ado\u00e7\u00e3o da eletromobilidade no pa\u00eds.<\/p>\n\n\n\n<p>Esse dinamismo transformou o cen\u00e1rio competitivo, no qual marcas tradicionais como Chevrolet e Toyota mant\u00eam participa\u00e7\u00e3o ativa, adaptando suas estrat\u00e9gias a um ambiente cada vez mais eletrificado.<\/p>\n\n\n\n<p><strong>Voc\u00ea tamb\u00e9m pode se interessar:<\/strong> <strong><a href=\"https:\/\/latamobility.com\/pt-br\/toyota-projeta-crescimento-de-vendas-e-reafirma-compromisso-com-a-mobilidade-hibrida-na-colombia-para-2026\/\">Toyota projeta crescimento de vendas e reafirma compromisso com a mobilidade h\u00edbrida na Col\u00f4mbia para 2026<\/a><\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-general-motors-desempenho-solido\"><strong>General Motors: desempenho s\u00f3lido<\/strong><\/h2>\n\n\n\n<p>A <strong>General Motors<\/strong>, por meio de sua marca <strong>Chevrolet<\/strong>, conseguiu consolidar uma oferta atraente no segmento de ve\u00edculos el\u00e9tricos na <strong>Col\u00f4mbia<\/strong>, tendo o <strong>Spark EUV<\/strong> como seu principal destaque.<\/p>\n\n\n\n<p>Durante mar\u00e7o de 2026, a empresa matriculou 194 unidades de ve\u00edculos el\u00e9tricos \u2014 o que representa <strong>um crescimento de 397,4%<\/strong> na compara\u00e7\u00e3o com o mesmo per\u00edodo do ano anterior. Esse desempenho colocou a Chevrolet como a <strong>quinta marca com maior volume de vendas no segmento el\u00e9trico<\/strong> no m\u00eas.<\/p>\n\n\n\n<p>O <strong>Chevrolet Spark EUV<\/strong> se tornou uma das alternativas mais atraentes para os colombianos que querem entrar na mobilidade com emiss\u00e3o zero. Desde seu lan\u00e7amento, esse SUV urbano se posicionou como <strong>o segundo ve\u00edculo mais vendido no segmento de SUV B el\u00e9trico<\/strong> no pa\u00eds, oferecendo autonomia de at\u00e9 360 quil\u00f4metros e pre\u00e7o competitivo em torno de 90 milh\u00f5es de pesos colombianos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Colombia-130426-b-1024x683.webp\" alt=\"Chevrolet\" class=\"wp-image-63867\" srcset=\"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Colombia-130426-b-1024x683.webp 1024w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Colombia-130426-b-300x200.webp 300w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Colombia-130426-b-768x512.webp 768w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Colombia-130426-b-600x400.webp 600w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Colombia-130426-b.webp 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>O reconhecimento da sua qualidade e proposta de valor n\u00e3o demorou: o Spark EUV foi eleito o <strong>Carro El\u00e9trico do Ano 2026 para a Am\u00e9rica do Sul<\/strong> pela Federa\u00e7\u00e3o Internacional do Jornalismo Automotivo (FIPA) \u2014 um pr\u00eamio que refor\u00e7a o bom momento da marca no mercado colombiano.<\/p>\n\n\n\n<p>Al\u00e9m dos n\u00fameros no segmento 100% el\u00e9trico, a Chevrolet tamb\u00e9m avan\u00e7ou na eletrifica\u00e7\u00e3o do seu portf\u00f3lio com modelos como a Captiva, dispon\u00edvel nas vers\u00f5es h\u00edbrida plug-in e totalmente el\u00e9trica, que v\u00eam encontrando um p\u00fablico crescente entre os compradores colombianos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"900\" height=\"600\" src=\"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Colombia-130426-c.webp\" alt=\"Chevrolet\" class=\"wp-image-63870\" srcset=\"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Colombia-130426-c.webp 900w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Colombia-130426-c-300x200.webp 300w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Colombia-130426-c-768x512.webp 768w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Colombia-130426-c-600x400.webp 600w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-toyota-lideranca-em-suvs-e-veiculos-off-road\"><strong>Toyota: lideran\u00e7a em SUVs e ve\u00edculos off-road<\/strong><\/h2>\n\n\n\n<p>A <strong>Toyota<\/strong>, uma das marcas mais emblem\u00e1ticas e tradicionais no mercado colombiano, adotou uma estrat\u00e9gia gradual rumo \u00e0 eletrifica\u00e7\u00e3o \u2014 apostando primeiro nos h\u00edbridos e agora dando os primeiros passos no segmento de el\u00e9tricos puros.<\/p>\n\n\n\n<p>Em mar\u00e7o de 2026, a montadora japonesa matriculou 56 ve\u00edculos 100% el\u00e9tricos, o que representa <strong>um crescimento impressionante de 2.700%<\/strong> nessa categoria \u2014 uma das maiores taxas de expans\u00e3o do mercado. Esse salto \u00e9 explicado pelo lan\u00e7amento oficial recente do seu primeiro modelo de emiss\u00e3o zero no pa\u00eds.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"620\" src=\"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Colombia-130426-e-1024x620.jpg\" alt=\"\" class=\"wp-image-63873\" srcset=\"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Colombia-130426-e-1024x620.jpg 1024w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Colombia-130426-e-300x182.jpg 300w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Colombia-130426-e-768x465.jpg 768w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Colombia-130426-e-600x363.jpg 600w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Colombia-130426-e.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>O <strong>Toyota bZ4X<\/strong>, um SUV m\u00e9dio 100% el\u00e9trico fabricado no Jap\u00e3o, representa a materializa\u00e7\u00e3o da vis\u00e3o &#8220;<strong>Beyond Zero<\/strong>&#8221; da empresa, focada em alcan\u00e7ar a neutralidade de carbono. Com autonomia de <strong>at\u00e9 480 quil\u00f4metros<\/strong> e equipado com o pacote de seguran\u00e7a Toyota Safety Sense 3.0, o <strong>bZ4X<\/strong> estreou oficialmente no mercado colombiano no in\u00edcio de 2026 (embora importa\u00e7\u00f5es independentes do modelo j\u00e1 fossem registradas desde 2024).<\/p>\n\n\n\n<p>Apesar de o volume de vendas el\u00e9tricas da Toyota ainda ser pequeno comparado a outros players, <strong>o crescimento exponencial de 2.700% em mar\u00e7o envia um sinal claro<\/strong> sobre o potencial da sua proposta e o crescente interesse dos consumidores colombianos por tecnologias de emiss\u00e3o zero. A empresa prev\u00ea que 2026 seja <strong>um ano de acelera\u00e7\u00e3o na ado\u00e7\u00e3o de ve\u00edculos eletrificados<\/strong> no pa\u00eds.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"693\" src=\"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Colombia-130426-f-1024x693.jpg\" alt=\"\" class=\"wp-image-63876\" srcset=\"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Colombia-130426-f-1024x693.jpg 1024w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Colombia-130426-f-300x203.jpg 300w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Colombia-130426-f-768x520.jpg 768w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Colombia-130426-f-600x406.jpg 600w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Colombia-130426-f.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-o-fenomeno-tesla\"><strong>O fen\u00f4meno Tesla<\/strong><\/h2>\n\n\n\n<p>O marco mais not\u00e1vel do m\u00eas foi, sem d\u00favida, o desempenho avassalador da <strong>Tesla<\/strong>. A <strong>Tesla <\/strong>come\u00e7ou as opera\u00e7\u00f5es na Col\u00f4mbia no final de 2025 e matriculou <strong>2.459 ve\u00edculos el\u00e9tricos<\/strong> durante mar\u00e7o \u2014 tornando-se a <strong>terceira marca mais vendida no mercado geral do pa\u00eds<\/strong> e a <strong>primeira no segmento el\u00e9trico, com 48,4% de participa\u00e7\u00e3o<\/strong>.<\/p>\n\n\n\n<p>Esse volume representou <strong>quase metade de todas as vendas de ve\u00edculos de emiss\u00e3o zero<\/strong> na Col\u00f4mbia durante o m\u00eas.<\/p>\n\n\n\n<p>O <strong>Tesla Model Y<\/strong> se tornou o primeiro ve\u00edculo el\u00e9trico a liderar as vendas mensais na Col\u00f4mbia, alcan\u00e7ando a impressionante marca de 1.791 unidades e uma participa\u00e7\u00e3o de 6,4% do mercado nacional \u2014 superando modelos tradicionais a combust\u00e3o. <\/p>\n\n\n\n<p>Por sua vez, o <strong>Tesla Model 3<\/strong> ficou na sexta posi\u00e7\u00e3o geral com 666 unidades, consolidando-se como o sed\u00e3 el\u00e9trico mais vendido do pa\u00eds.<\/p>\n\n\n\n<p>O sucesso da <strong>Tesla <\/strong>\u00e9 resultado de uma combina\u00e7\u00e3o de fatores: a entrega em massa de reservas acumuladas por v\u00e1rios meses, uma <strong>estrat\u00e9gia de pre\u00e7os agressiva<\/strong> que pressionou os custos dos ve\u00edculos el\u00e9tricos para baixo, e o crescente interesse dos colombianos por mobilidade sustent\u00e1vel \u2014 incentivado tamb\u00e9m por benef\u00edcios fiscais como o <strong>IVA reduzido de 5% para el\u00e9tricos<\/strong> (contra 19% dos ve\u00edculos a combust\u00e3o).<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Colombia-130426-g-1024x576.jpg\" alt=\"\" class=\"wp-image-63885\" srcset=\"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Colombia-130426-g-1024x576.jpg 1024w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Colombia-130426-g-300x169.jpg 300w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Colombia-130426-g-768x432.jpg 768w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Colombia-130426-g-600x338.jpg 600w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Colombia-130426-g.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-panorama-geral\"><strong>Panorama geral<\/strong><\/h2>\n\n\n\n<p>O dinamismo do mercado de ve\u00edculos el\u00e9tricos na <strong>Col\u00f4mbia <\/strong>n\u00e3o se limita aos principais players. <\/p>\n\n\n\n<p>A <strong>BYD<\/strong>, a gigante chinesa que tradicionalmente liderava o segmento, continua sendo uma forte concorrente, mesmo tendo cedido o primeiro lugar para a <strong>Tesla<\/strong>. Durante mar\u00e7o, a <strong>BYD <\/strong>matriculou 906 unidades, com crescimento de <strong>9,2%<\/strong>, e acumula 2.684 unidades no primeiro trimestre do ano \u2014 muito perto da lideran\u00e7a. Seu modelo <strong>Yuan Up<\/strong> continua sendo um dos favoritos do mercado, com 616 unidades em mar\u00e7o.<\/p>\n\n\n\n<p>Outras marcas tamb\u00e9m tiveram crescimentos extraordin\u00e1rios no segmento el\u00e9trico:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>A <strong>Chery<\/strong>, impulsionada pelo bem-sucedido iCAR 03, registrou 263 unidades em mar\u00e7o \u2014 <strong>crescimento superior a 4.000%<\/strong> na compara\u00e7\u00e3o com o mesmo m\u00eas de 2025.<\/li>\n\n\n\n<li>A <strong>MG<\/strong>, com seu modelo S5 EV, alcan\u00e7ou 240 unidades e <strong>crescimento de 757,1%<\/strong>.<\/li>\n\n\n\n<li>A <strong>GAC<\/strong>, embora com volume ainda modesto, registrou a maior taxa de expans\u00e3o do mercado: <strong>aumento de 5.900%<\/strong> nas vendas de el\u00e9tricos.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"993\" height=\"716\" src=\"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Colombia-130426-h.jpg\" alt=\"Chevrolet\" class=\"wp-image-63879\" srcset=\"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Colombia-130426-h.jpg 993w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Colombia-130426-h-300x216.jpg 300w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Colombia-130426-h-768x554.jpg 768w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Colombia-130426-h-600x433.jpg 600w\" sizes=\"(max-width: 993px) 100vw, 993px\" \/><\/figure>\n\n\n\n<p>No acumulado do primeiro trimestre de 2026, foram matriculados <strong>9.349 novos ve\u00edculos el\u00e9tricos<\/strong> na <strong>Col\u00f4mbia <\/strong>\u2014 <strong>crescimento de 171,3%<\/strong> em rela\u00e7\u00e3o ao mesmo per\u00edodo de 2025. Comparado ao primeiro trimestre de 2024, quando apenas 992 unidades el\u00e9tricas foram registradas, o crescimento foi de <strong>842% em apenas dois anos<\/strong>. Essa tend\u00eancia mostra que <strong>a eletromobilidade est\u00e1 se consolidando<\/strong> no pa\u00eds.<\/p>\n\n\n\n<p>O futuro do segmento el\u00e9trico na <strong>Col\u00f4mbia <\/strong>parece promissor. Com a chegada de novos players, a amplia\u00e7\u00e3o da oferta de marcas tradicionais como Chevrolet e Toyota, e os incentivos fiscais que continuam valendo, espera-se que o crescimento se mantenha nos pr\u00f3ximos meses.<\/p>\n\n\n\n<p><strong>A eletromobilidade deixou de ser uma promessa para se tornar uma realidade tang\u00edvel nas ruas colombianas.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"996\" height=\"718\" src=\"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Colombia-130426-i.jpg\" alt=\"\" class=\"wp-image-63882\" srcset=\"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Colombia-130426-i.jpg 996w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Colombia-130426-i-300x216.jpg 300w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Colombia-130426-i-768x554.jpg 768w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Colombia-130426-i-600x433.jpg 600w\" sizes=\"(max-width: 996px) 100vw, 996px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-um-2026-de-consolidacao-para-a-mobilidade\">Um 2026 de Consolida\u00e7\u00e3o para a Mobilidade<\/h2>\n\n\n\n<p>O <strong>Latam Mobility 2026 Tour<\/strong> continua sua jornada pela regi\u00e3o, com o pr\u00f3ximo encontro acontecendo em <strong><a href=\"https:\/\/latamobility.com\/pt-br\/summit\/latam-mobility-netzero-brazil-2026\/\">S\u00e3o Paulo, Brasil<\/a>, nos dias 15 e 16 de abril<\/strong>. L\u00e1, l\u00edderes dos setores p\u00fablico e privado se reunir\u00e3o para analisar os avan\u00e7os e desafios da mobilidade sustent\u00e1vel, a eletrifica\u00e7\u00e3o dos transportes e as novas oportunidades para a transi\u00e7\u00e3o energ\u00e9tica na Am\u00e9rica Latina.<\/p>\n\n\n\n<p>Este evento se consolidou como uma plataforma fundamental para conectar empresas, autoridades, startups e institui\u00e7\u00f5es que impulsionam solu\u00e7\u00f5es inovadoras em transporte limpo, infraestrutura de recarga, energias renov\u00e1veis \u200b\u200be novas tecnologias para a mobilidade do futuro.<\/p>\n\n\n\n<p>Ap\u00f3s o <strong>Brasil<\/strong>, o tour seguir\u00e1 para <strong><a href=\"https:\/\/latamobility.com\/pt-br\/summit\/latam-mobility-colombia-2026\/\">Medell\u00edn, Col\u00f4mbia<\/a>, nos dias 10 e 11 de junho<\/strong>, e chegar\u00e1 a <strong><a href=\"https:\/\/latamobility.com\/pt-br\/summit\/latam-mobility-conosur-2026\/\">Santiago, Chile<\/a>, no dia 25 de agosto<\/strong>, reunindo especialistas e atores estrat\u00e9gicos para fortalecer ainda mais o ecossistema de mobilidade sustent\u00e1vel na regi\u00e3o.<\/p>\n\n\n\n<p>A turn\u00ea ser\u00e1 conclu\u00edda na <strong><a href=\"https:\/\/latamobility.com\/pt-br\/summit\/latam-mobility-mexico-2026\/\">Cidade do M\u00e9xico<\/a>, nos dias 12 e 13 de outubro<\/strong>, em paralelo ao <strong>Climate Economy Forum<\/strong>, em um evento que reunir\u00e1 l\u00edderes do setor para impulsionar ainda mais a transi\u00e7\u00e3o para sistemas de transporte mais eficientes, sustent\u00e1veis \u200b\u200be de baixa emiss\u00e3o na Am\u00e9rica Latina.<\/p>\n\n\n\n<p>A transi\u00e7\u00e3o j\u00e1 est\u00e1 em andamento. A <strong>Latam Mobility Tour 2026 <\/strong>ser\u00e1 o ponto de encontro para acelerar decis\u00f5es, conectar as principais partes interessadas e construir, de forma colaborativa, uma mobilidade sustent\u00e1vel na Am\u00e9rica Latina.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/03\/Gira-IIL.jpg-1024x576.jpeg\" alt=\"\" class=\"wp-image-61124\" srcset=\"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/03\/Gira-IIL.jpg-1024x576.jpeg 1024w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/03\/Gira-IIL.jpg-300x169.jpeg 300w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/03\/Gira-IIL.jpg-768x432.jpeg 768w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/03\/Gira-IIL.jpg-1536x864.jpeg 1536w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/03\/Gira-IIL.jpg-2048x1153.jpeg 2048w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/03\/Gira-IIL.jpg-600x338.jpeg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>O mercado de ve\u00edculos el\u00e9tricos na Col\u00f4mbia viveu um mar\u00e7o hist\u00f3rico, com crescimento de 267% impulsionado pela entrada da Tesla no mercado local. De acordo com o relat\u00f3rio mais recente da Associa\u00e7\u00e3o Nacional de Mobilidade Sustent\u00e1vel (Andemos), foram matriculados 5.083 ve\u00edculos de emiss\u00e3o zero durante o terceiro m\u00eas do ano \u2014 um n\u00famero que mostra&#8230;<\/p>\n","protected":false},"author":10,"featured_media":63864,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[2356],"tags":[3382,3431,2568,3325],"class_list":["post-63890","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-movilidad-electrica-pt-br","tag-chevrolet-3","tag-colombia-pt-br","tag-general-motors-3","tag-toyota-pt-br"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>General Motors e Toyota registram crescimento hist\u00f3rico em ve\u00edculos el\u00e9tricos na Col\u00f4mbia - Latam Mobility<\/title>\n<meta name=\"description\" content=\"Tesla impulsionou crescimento de 267% nos el\u00e9tricos da Col\u00f4mbia em mar\u00e7o de 2026. GM cresceu 397%, Toyota 2.700%\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/latamobility.com\/?p=63860\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"General Motors e Toyota registram crescimento hist\u00f3rico em ve\u00edculos el\u00e9tricos na Col\u00f4mbia\" \/>\n<meta property=\"og:description\" content=\"Tesla impulsionou crescimento de 267% nos el\u00e9tricos da Col\u00f4mbia em mar\u00e7o de 2026. GM cresceu 397%, Toyota 2.700%\" \/>\n<meta property=\"og:url\" content=\"https:\/\/latamobility.com\/?p=63860\" \/>\n<meta property=\"og:site_name\" content=\"Latam Mobility\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/latamobility\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-15T10:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Colombia-130426-a.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Antonio Vilela\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"Tesla impulsionou crescimento de 267% nos el\u00e9tricos da Col\u00f4mbia em mar\u00e7o de 2026. GM cresceu 397%, Toyota 2.700%\" \/>\n<meta name=\"twitter:creator\" content=\"@LataMobility\" \/>\n<meta name=\"twitter:site\" content=\"@LataMobility\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Antonio Vilela\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/latamobility.com\\\/?p=63860#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/latamobility.com\\\/?p=63860\"},\"author\":{\"name\":\"Antonio Vilela\",\"@id\":\"https:\\\/\\\/latamobility.com\\\/#\\\/schema\\\/person\\\/fda092a2de1f87d347784282908bad1a\"},\"headline\":\"General Motors e Toyota registram crescimento hist\u00f3rico em ve\u00edculos el\u00e9tricos na Col\u00f4mbia\",\"datePublished\":\"2026-04-15T10:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/latamobility.com\\\/?p=63860\"},\"wordCount\":1391,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/latamobility.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/latamobility.com\\\/?p=63860#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/latamobility.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Colombia-130426-a.jpg\",\"keywords\":[\"Chevrolet\",\"Colombia\",\"General Motors\",\"Toyota\"],\"articleSection\":[\"Movilidad el\u00e9ctrica\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/latamobility.com\\\/?p=63860#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/latamobility.com\\\/?p=63860\",\"url\":\"https:\\\/\\\/latamobility.com\\\/?p=63860\",\"name\":\"General Motors e Toyota registram crescimento hist\u00f3rico em ve\u00edculos el\u00e9tricos na Col\u00f4mbia - Latam Mobility\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/latamobility.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/latamobility.com\\\/?p=63860#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/latamobility.com\\\/?p=63860#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/latamobility.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Colombia-130426-a.jpg\",\"datePublished\":\"2026-04-15T10:00:00+00:00\",\"description\":\"Tesla impulsionou crescimento de 267% nos el\u00e9tricos da Col\u00f4mbia em mar\u00e7o de 2026. GM cresceu 397%, Toyota 2.700%\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/latamobility.com\\\/?p=63860#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/latamobility.com\\\/?p=63860\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/latamobility.com\\\/?p=63860#primaryimage\",\"url\":\"https:\\\/\\\/latamobility.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Colombia-130426-a.jpg\",\"contentUrl\":\"https:\\\/\\\/latamobility.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Colombia-130426-a.jpg\",\"width\":1280,\"height\":720,\"caption\":\"Chevrolet\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/latamobility.com\\\/?p=63860#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/latamobility.com\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"General Motors e Toyota registram crescimento hist\u00f3rico em ve\u00edculos el\u00e9tricos na Col\u00f4mbia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/latamobility.com\\\/#website\",\"url\":\"https:\\\/\\\/latamobility.com\\\/\",\"name\":\"Latam Mobility\",\"description\":\"Serie de Eventos para promover la Movilidad y Transporte sostenible en Latinoam\u00e9rica\",\"publisher\":{\"@id\":\"https:\\\/\\\/latamobility.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/latamobility.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/latamobility.com\\\/#organization\",\"name\":\"LATAM MOBILITY\",\"url\":\"https:\\\/\\\/latamobility.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/latamobility.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/latamobility.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/logos-LM-LG-2025-10.png\",\"contentUrl\":\"https:\\\/\\\/latamobility.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/logos-LM-LG-2025-10.png\",\"width\":1080,\"height\":1080,\"caption\":\"LATAM MOBILITY\"},\"image\":{\"@id\":\"https:\\\/\\\/latamobility.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/latamobility\\\/\",\"https:\\\/\\\/x.com\\\/LataMobility\",\"https:\\\/\\\/www.instagram.com\\\/latamobility\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/latamobility\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCtcslRCRY0vITWaOQ1X0XUA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/latamobility.com\\\/#\\\/schema\\\/person\\\/fda092a2de1f87d347784282908bad1a\",\"name\":\"Antonio Vilela\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7eee8196fd2fda180806d7b41cd517f274d5ad3b9f65d873feb3ca7e2b3a72d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7eee8196fd2fda180806d7b41cd517f274d5ad3b9f65d873feb3ca7e2b3a72d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7eee8196fd2fda180806d7b41cd517f274d5ad3b9f65d873feb3ca7e2b3a72d2?s=96&d=mm&r=g\",\"caption\":\"Antonio Vilela\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"General Motors e Toyota registram crescimento hist\u00f3rico em ve\u00edculos el\u00e9tricos na Col\u00f4mbia - Latam Mobility","description":"Tesla impulsionou crescimento de 267% nos el\u00e9tricos da Col\u00f4mbia em mar\u00e7o de 2026. GM cresceu 397%, Toyota 2.700%","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/latamobility.com\/?p=63860","og_locale":"pt_BR","og_type":"article","og_title":"General Motors e Toyota registram crescimento hist\u00f3rico em ve\u00edculos el\u00e9tricos na Col\u00f4mbia","og_description":"Tesla impulsionou crescimento de 267% nos el\u00e9tricos da Col\u00f4mbia em mar\u00e7o de 2026. GM cresceu 397%, Toyota 2.700%","og_url":"https:\/\/latamobility.com\/?p=63860","og_site_name":"Latam Mobility","article_publisher":"https:\/\/www.facebook.com\/latamobility\/","article_published_time":"2026-04-15T10:00:00+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Colombia-130426-a.jpg","type":"image\/jpeg"}],"author":"Antonio Vilela","twitter_card":"summary_large_image","twitter_description":"Tesla impulsionou crescimento de 267% nos el\u00e9tricos da Col\u00f4mbia em mar\u00e7o de 2026. GM cresceu 397%, Toyota 2.700%","twitter_creator":"@LataMobility","twitter_site":"@LataMobility","twitter_misc":{"Escrito por":"Antonio Vilela","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/latamobility.com\/?p=63860#article","isPartOf":{"@id":"https:\/\/latamobility.com\/?p=63860"},"author":{"name":"Antonio Vilela","@id":"https:\/\/latamobility.com\/#\/schema\/person\/fda092a2de1f87d347784282908bad1a"},"headline":"General Motors e Toyota registram crescimento hist\u00f3rico em ve\u00edculos el\u00e9tricos na Col\u00f4mbia","datePublished":"2026-04-15T10:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/latamobility.com\/?p=63860"},"wordCount":1391,"commentCount":0,"publisher":{"@id":"https:\/\/latamobility.com\/#organization"},"image":{"@id":"https:\/\/latamobility.com\/?p=63860#primaryimage"},"thumbnailUrl":"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Colombia-130426-a.jpg","keywords":["Chevrolet","Colombia","General Motors","Toyota"],"articleSection":["Movilidad el\u00e9ctrica"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/latamobility.com\/?p=63860#respond"]}]},{"@type":"WebPage","@id":"https:\/\/latamobility.com\/?p=63860","url":"https:\/\/latamobility.com\/?p=63860","name":"General Motors e Toyota registram crescimento hist\u00f3rico em ve\u00edculos el\u00e9tricos na Col\u00f4mbia - Latam Mobility","isPartOf":{"@id":"https:\/\/latamobility.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/latamobility.com\/?p=63860#primaryimage"},"image":{"@id":"https:\/\/latamobility.com\/?p=63860#primaryimage"},"thumbnailUrl":"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Colombia-130426-a.jpg","datePublished":"2026-04-15T10:00:00+00:00","description":"Tesla impulsionou crescimento de 267% nos el\u00e9tricos da Col\u00f4mbia em mar\u00e7o de 2026. GM cresceu 397%, Toyota 2.700%","breadcrumb":{"@id":"https:\/\/latamobility.com\/?p=63860#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/latamobility.com\/?p=63860"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/latamobility.com\/?p=63860#primaryimage","url":"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Colombia-130426-a.jpg","contentUrl":"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Colombia-130426-a.jpg","width":1280,"height":720,"caption":"Chevrolet"},{"@type":"BreadcrumbList","@id":"https:\/\/latamobility.com\/?p=63860#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/latamobility.com\/pt-br\/"},{"@type":"ListItem","position":2,"name":"General Motors e Toyota registram crescimento hist\u00f3rico em ve\u00edculos el\u00e9tricos na Col\u00f4mbia"}]},{"@type":"WebSite","@id":"https:\/\/latamobility.com\/#website","url":"https:\/\/latamobility.com\/","name":"Latam Mobility","description":"Serie de Eventos para promover la Movilidad y Transporte sostenible en Latinoam\u00e9rica","publisher":{"@id":"https:\/\/latamobility.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/latamobility.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/latamobility.com\/#organization","name":"LATAM MOBILITY","url":"https:\/\/latamobility.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/latamobility.com\/#\/schema\/logo\/image\/","url":"https:\/\/latamobility.com\/wp-content\/uploads\/2025\/01\/logos-LM-LG-2025-10.png","contentUrl":"https:\/\/latamobility.com\/wp-content\/uploads\/2025\/01\/logos-LM-LG-2025-10.png","width":1080,"height":1080,"caption":"LATAM MOBILITY"},"image":{"@id":"https:\/\/latamobility.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/latamobility\/","https:\/\/x.com\/LataMobility","https:\/\/www.instagram.com\/latamobility\/","https:\/\/www.linkedin.com\/company\/latamobility\/","https:\/\/www.youtube.com\/channel\/UCtcslRCRY0vITWaOQ1X0XUA"]},{"@type":"Person","@id":"https:\/\/latamobility.com\/#\/schema\/person\/fda092a2de1f87d347784282908bad1a","name":"Antonio Vilela","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/7eee8196fd2fda180806d7b41cd517f274d5ad3b9f65d873feb3ca7e2b3a72d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7eee8196fd2fda180806d7b41cd517f274d5ad3b9f65d873feb3ca7e2b3a72d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7eee8196fd2fda180806d7b41cd517f274d5ad3b9f65d873feb3ca7e2b3a72d2?s=96&d=mm&r=g","caption":"Antonio Vilela"}}]}},"_links":{"self":[{"href":"https:\/\/latamobility.com\/pt-br\/wp-json\/wp\/v2\/posts\/63890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/latamobility.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latamobility.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latamobility.com\/pt-br\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/latamobility.com\/pt-br\/wp-json\/wp\/v2\/comments?post=63890"}],"version-history":[{"count":1,"href":"https:\/\/latamobility.com\/pt-br\/wp-json\/wp\/v2\/posts\/63890\/revisions"}],"predecessor-version":[{"id":63891,"href":"https:\/\/latamobility.com\/pt-br\/wp-json\/wp\/v2\/posts\/63890\/revisions\/63891"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latamobility.com\/pt-br\/wp-json\/wp\/v2\/media\/63864"}],"wp:attachment":[{"href":"https:\/\/latamobility.com\/pt-br\/wp-json\/wp\/v2\/media?parent=63890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latamobility.com\/pt-br\/wp-json\/wp\/v2\/categories?post=63890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latamobility.com\/pt-br\/wp-json\/wp\/v2\/tags?post=63890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}