{"id":64866,"date":"2026-05-08T05:00:00","date_gmt":"2026-05-08T10:00:00","guid":{"rendered":"https:\/\/latamobility.com\/?p=64866"},"modified":"2026-05-08T10:15:01","modified_gmt":"2026-05-08T15:15:01","slug":"canal-solar-aposta-no-armazenamento-bes-como-solucao-para-recarga-de-veiculos","status":"publish","type":"post","link":"https:\/\/latamobility.com\/pt-br\/canal-solar-aposta-no-armazenamento-bes-como-solucao-para-recarga-de-veiculos\/","title":{"rendered":"Canal Solar aposta no armazenamento BESS como solu\u00e7\u00e3o para recarga de ve\u00edculos"},"content":{"rendered":"\n<p>No \u00e2mbito do <strong>Latam Mobility &amp; Net Zero Brasil 2026<\/strong>, o CEO do <strong>Canal Solar<\/strong>, <strong>Bernardo Marang\u00f3n<\/strong>, apresentou a palestra intitulada <strong>&#8220;Quando a energia solar encontra o asfalto&#8221;<\/strong> .<\/p>\n\n\n\n<p>Durante sua fala, o especialista do setor el\u00e9trico brasileiro tra\u00e7ou um paralelo entre o <strong>crescimento explosivo da energia solar fotovoltaica no Brasil<\/strong> e o potencial igualmente disruptivo da <strong>eletromobilidade<\/strong>. Sua mensagem foi direta: <strong>o setor el\u00e9trico e a mobilidade compartilham o mesmo futuro, e esse futuro \u00e9 agora.<\/strong><\/p>\n\n\n\n<p><strong>Bernardo Marang\u00f3n<\/strong> \u2013 reconhecido no setor por seu trabalho \u00e0 frente do <strong>Canal Solar<\/strong> e como impulsionador do <strong>Canal VE<\/strong> (iniciativa que une o setor el\u00e9trico \u00e0 eletromobilidade) \u2013 come\u00e7ou sua apresenta\u00e7\u00e3o destacando um dado: <strong>a matriz el\u00e9trica do Brasil \u00e9 majoritariamente renov\u00e1vel.<\/strong><\/p>\n\n\n\n<p><strong>&#8220;Isso \u00e9 algo do qual temos que nos orgulhar&#8221;<\/strong> , afirmou. E acrescentou que, embora a fonte h\u00eddrica tenha sido historicamente a principal, <strong>a energia solar se tornou a segunda fonte mais importante do pa\u00eds em muito pouco tempo.<\/strong><\/p>\n\n\n\n<p><strong>Voc\u00ea tamb\u00e9m pode se interessar por | <a href=\"https:\/\/latamobility.com\/pt-br\/papo-de-garagem-latam-mobility-brasil-2026-pacto-competitividade-montadoras-e-tecnologias\/\">&#8220;Papo de Garagem&#8221; prop\u00f5e no Latam Mobility Brasil 2026 um pacto pela competitividade que transcenda montadoras e tecnologias<\/a><\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-o-tsunami-da-energia-solar\"><strong>O tsunami da energia solar<\/strong><\/h2>\n\n\n\n<p>Um dos momentos mais marcantes da apresenta\u00e7\u00e3o foi quando <strong>Bernardo Marang\u00f3n<\/strong> colocou em perspectiva o crescimento do setor solar no Brasil.<\/p>\n\n\n\n<p><strong>&#8220;Em 2018, inaugurei uma usina de meio megawatt em S\u00e3o Paulo e com isso aumentei em 30% a capacidade instalada do estado. Em nove anos, passamos de pouco mais de 30 megawatts para 55 gigawatts. Isso foi uma onda, um tsunami de oportunidades&#8221;<\/strong> , enfatizou.<\/p>\n\n\n\n<p>O executivo do <strong>Canal Solar<\/strong> explicou que esse crescimento vertiginoso abriu um mundo de possibilidades para integradores, distribuidores de equipamentos e toda uma cadeia de valor. No entanto, alertou que, devido a mudan\u00e7as nas regras de compensa\u00e7\u00e3o, o setor solar entrou em um <strong>planalto<\/strong>.<\/p>\n\n\n\n<p><strong>&#8220;Continua crescendo, mas j\u00e1 n\u00e3o \u00e9 o mercado de crescimento exponencial de antes&#8221;<\/strong> , assinalou. E foi a\u00ed que ele introduziu sua tese principal: <strong>a eletromobilidade \u00e9 hoje o setor de grande oportunidade, compar\u00e1vel ao solar de 2018.<\/strong><\/p>\n\n\n\n<p>&#8220;Eu lembro de 2018, quando comecei no solar, e espero que dentro de nove anos a curva da eletromobilidade seja um pontinho no final de uma curva exponencial. Este setor vai ter um crescimento fort\u00edssimo&#8221;, garantiu.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/05\/Canal-Solar-b-1024x683.jpg\" alt=\"Canal Solar\" class=\"wp-image-64856\" srcset=\"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/05\/Canal-Solar-b-1024x683.jpg 1024w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/05\/Canal-Solar-b-300x200.jpg 300w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/05\/Canal-Solar-b-768x512.jpg 768w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/05\/Canal-Solar-b-1536x1024.jpg 1536w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/05\/Canal-Solar-b-600x400.jpg 600w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/05\/Canal-Solar-b.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-a-necessidade-de-construir-algo-que-perdure\"><strong>A necessidade de construir algo que perdure<\/strong><\/h2>\n\n\n\n<p><strong>Bernardo Marang\u00f3n<\/strong> compartilhou uma li\u00e7\u00e3o aprendida na ind\u00fastria solar: <strong>&#8220;Para ter sucesso em qualquer coisa que voc\u00ea queira fazer, o ideal \u00e9 estar em um setor de alto crescimento. Eu costumo dizer que s\u00e3o neg\u00f3cios \u00e0 prova de idiotas: qualquer um que entra num mercado em grande crescimento vai ganhar dinheiro.&#8221;<\/strong><\/p>\n\n\n\n<p>Mas alertou que a maioria daqueles que fizeram neg\u00f3cios no setor solar n\u00e3o construiu algo que perdurasse. <strong>&#8220;Voc\u00ea vai ter capital, vai ter pessoas interessadas em entrar, mas voc\u00ea precisa ter a capacidade de construir algo que permane\u00e7a&#8221;<\/strong> , refletiu.<\/p>\n\n\n\n<p>Al\u00e9m disso, o CEO do <strong>Canal Solar<\/strong> identificou o principal obst\u00e1culo para a <strong>massifica\u00e7\u00e3o do ve\u00edculo el\u00e9trico<\/strong>: a <strong>infraestrutura de recarga<\/strong>. <strong>&#8220;Como esses carros v\u00e3o ser carregados, seja em casa ou na rua, atrav\u00e9s de esta\u00e7\u00f5es de recarga?&#8221;<\/strong> , perguntou, e apontou que as redes de distribui\u00e7\u00e3o t\u00eam capacidade limitada.<\/p>\n\n\n\n<p>Ele deu o exemplo do que foi visto no <strong>Latam Mobility Brasil 2026<\/strong> sobre garagens de \u00f4nibus: &#8220;A capacidade da distribuidora para carregar os \u00f4nibus \u00e9 limitada. Ou voc\u00ea amplia a rede \u2013 o que \u00e9 muito dif\u00edcil em cidades como S\u00e3o Paulo, onde j\u00e1 n\u00e3o h\u00e1 pot\u00eancia dispon\u00edvel \u2013 ou voc\u00ea busca outra solu\u00e7\u00e3o.&#8221;<\/p>\n\n\n\n<p>Essa solu\u00e7\u00e3o, segundo Marang\u00f3n, \u00e9 o <strong>BESS <\/strong>(Battery Energy Storage System), ou sistema de armazenamento de energia em baterias. <strong>&#8220;Enquanto houver limite de crescimento das redes, o BESS aparece como uma possibilidade para atender a demanda que a recarga vai exigir, seja em garagens de \u00f4nibus ou em condom\u00ednios&#8221;<\/strong> , explicou.<\/p>\n\n\n\n<p>E lan\u00e7ou uma previs\u00e3o: <strong>&#8220;Todas as vagas de estacionamento v\u00e3o ter um carregador.&#8221;<\/strong> Isso gerar\u00e1 um problema de demanda nos condom\u00ednios, e a distribuidora n\u00e3o ter\u00e1 capacidade de ampliar a rede na velocidade necess\u00e1ria. <strong>&#8220;Por isso a solu\u00e7\u00e3o est\u00e1 no BESS&#8221;<\/strong> , afirmou.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-o-ecossistema-solar-migra-para-a-eletromobilidade\"><strong>O ecossistema solar migra para a eletromobilidade<\/strong><\/h2>\n\n\n\n<p><strong>Bernardo Marang\u00f3n<\/strong> destacou um fen\u00f4meno que j\u00e1 est\u00e1 acontecendo: o ecossistema da energia solar est\u00e1 <strong>abra\u00e7ando a eletromobilidade<\/strong>. <strong>&#8220;Vejo fornecedores e integradores que trabalhavam com placas solares e inversores, e hoje instalam ou vendem esta\u00e7\u00f5es de recarga&#8221;<\/strong> , relatou.<\/p>\n\n\n\n<p>E observou que essa migra\u00e7\u00e3o ajudar\u00e1 a acelerar o crescimento, porque o setor solar j\u00e1 construiu uma estrutura de importadores, fabricantes locais e canais de distribui\u00e7\u00e3o. <strong>&#8220;A estrutura j\u00e1 est\u00e1 montada. Por consequ\u00eancia, vamos crescer a uma velocidade muito maior&#8221;<\/strong> , garantiu.<\/p>\n\n\n\n<p>Um dos pontos mais inovadores de sua exposi\u00e7\u00e3o foi o conceito de <strong>V2G (Vehicle to Grid)<\/strong> ou <strong>V2L (Vehicle to Load)<\/strong>. Marang\u00f3n comparou a bateria de um carro el\u00e9trico \u2013 cerca de 35 kWh em um ve\u00edculo pequeno \u2013 com a necessidade de uma resid\u00eancia, que com 5 kWh pode funcionar v\u00e1rias horas durante uma queda de energia.<\/p>\n\n\n\n<p><strong>&#8220;Um carro pequeno tem sete vezes a necessidade da minha casa. Eu poderia ficar um ou dois dias sem energia, e se a bateria acabar, posso ir a uma esta\u00e7\u00e3o de recarga e voltar com ela&#8221;<\/strong> , explicou. Para ele, esse \u00e9 um neg\u00f3cio de <strong>grande potencial<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-multiplas-oportunidades\"><strong>M\u00faltiplas oportunidades<\/strong><\/h2>\n\n\n\n<p>Durante sua interven\u00e7\u00e3o no <strong>Latam Mobility Brasil 2026<\/strong>, <strong>Bernardo Marang\u00f3n<\/strong> detalhou as quatro grandes \u00e1reas de oportunidade que ele enxerga:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Gera\u00e7\u00e3o solar<\/strong>: ainda tem espa\u00e7o, especialmente no mercado livre (clientes de alta tens\u00e3o) e na modalidade de gera\u00e7\u00e3o compartilhada, onde os pre\u00e7os atuais tornam a energia solar competitiva para f\u00e1bricas e com\u00e9rcios.<\/li>\n\n\n\n<li><strong>BESS (armazenamento)<\/strong> : \u00e9 um mercado que est\u00e1 come\u00e7ando agora, mas tem potencial de investimento ainda maior que o da energia solar, porque as baterias podem ser instaladas at\u00e9 mesmo em apartamentos \u2013 um cliente que a energia solar n\u00e3o conseguia alcan\u00e7ar.<\/li>\n\n\n\n<li><strong>Eletropostos (esta\u00e7\u00f5es de recarga)<\/strong> : s\u00e3o a infraestrutura necess\u00e1ria para que carros, caminh\u00f5es e \u00f4nibus possam ser carregados.<\/li>\n\n\n\n<li><strong>Condom\u00ednios<\/strong>: ser\u00e3o um mercado enorme porque todas as suas garagens v\u00e3o precisar de carregadores.<\/li>\n<\/ul>\n\n\n\n<p>O CEO do <strong>Canal Solar<\/strong> tamb\u00e9m destacou o papel da <strong>educa\u00e7\u00e3o<\/strong>. <strong>&#8220;No mundo da educa\u00e7\u00e3o, damos aulas de como instalar gera\u00e7\u00e3o solar. Hoje nosso best-seller \u00e9 o curso de BESS, onde capacitamos mais de 100 pessoas por m\u00eas&#8221;<\/strong> , revelou. E anunciou que no segundo semestre lan\u00e7ar\u00e3o um novo curso sobre a <strong>integra\u00e7\u00e3o da eletromobilidade<\/strong>.<\/p>\n\n\n\n<p>Em seu encerramento, <strong>Bernardo Marang\u00f3n<\/strong> resumiu sua vis\u00e3o: <strong>&#8220;A energia solar vai ajudar a reduzir o custo, o BESS vai ajudar com a quest\u00e3o da demanda e da qualidade da energia, e os carregadores \u2013 talvez n\u00e3o os de um megawatt em cinco minutos porque seriam muito caros, mas n\u00e3o duvido da capacidade dos chineses de baratear solu\u00e7\u00f5es \u2013 v\u00e3o estar em todas as garagens.&#8221;<\/strong><\/p>\n\n\n\n<p>E deixou uma frase: <strong>&#8220;O setor el\u00e9trico e a mobilidade s\u00e3o o mesmo futuro, e a hora \u00e9 agora.&#8221;<\/strong> Em seguida, convidou a audi\u00eancia a se juntar a essa onda, assegurando que dentro de nove anos muitos dos presentes estar\u00e3o vendo essa curva exponencial no ponto mais alto.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/05\/Canal-Solar-c-1024x683.jpg\" alt=\"Canal Solar\" class=\"wp-image-64859\" srcset=\"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/05\/Canal-Solar-c-1024x683.jpg 1024w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/05\/Canal-Solar-c-300x200.jpg 300w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/05\/Canal-Solar-c-768x512.jpg 768w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/05\/Canal-Solar-c-1536x1024.jpg 1536w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/05\/Canal-Solar-c-600x400.jpg 600w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/05\/Canal-Solar-c.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-um-2026-de-consolidacao-para-a-mobilidade\">Um 2026 de consolida\u00e7\u00e3o para a mobilidade<\/h2>\n\n\n\n<p>O <strong>Tour Latam Mobility 2026<\/strong> continua sua jornada. O pr\u00f3ximo encontro ser\u00e1 em <strong><a href=\"https:\/\/latamobility.com\/pt-br\/summit\/latam-mobility-colombia-2026\/\">Medell\u00edn, Col\u00f4mbia<\/a><\/strong>, nos dias <strong>10 e 11 de junho<\/strong>, e depois chegar\u00e1 a <strong><a href=\"https:\/\/latamobility.com\/pt-br\/summit\/latam-mobility-conosur-2026\/\">Santiago, Chile<\/a><\/strong>, em <strong>25 de agosto<\/strong>, reunindo especialistas e atores estrat\u00e9gicos para fortalecer ainda mais o ecossistema de mobilidade sustent\u00e1vel na regi\u00e3o.<\/p>\n\n\n\n<p>O tour terminar\u00e1 na <strong><a href=\"https:\/\/latamobility.com\/pt-br\/summit\/latam-mobility-mexico-2026\/\">Cidade do M\u00e9xico<\/a><\/strong> nos dias <strong>12 e 13 de outubro<\/strong>, junto com o <strong>Climate Economy Forum<\/strong>, num evento que reunir\u00e1 grandes refer\u00eancias do setor para continuar impulsionando a transi\u00e7\u00e3o para sistemas de transporte mais eficientes, sustent\u00e1veis e de baixas emiss\u00f5es na Am\u00e9rica Latina.<\/p>\n\n\n\n<p><strong>A transi\u00e7\u00e3o j\u00e1 est\u00e1 em curso.<\/strong> O Tour 2026 da <strong>Latam Mobility<\/strong> ser\u00e1 o ponto de encontro para acelerar decis\u00f5es, conectar os atores\u2011chave e construir, de forma colaborativa, a <strong>mobilidade sustent\u00e1vel da Am\u00e9rica Latina<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Gira-IIL.jpg-1-1024x576.jpeg\" alt=\"\" class=\"wp-image-63893\" srcset=\"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Gira-IIL.jpg-1-1024x576.jpeg 1024w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Gira-IIL.jpg-1-300x169.jpeg 300w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Gira-IIL.jpg-1-768x432.jpeg 768w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Gira-IIL.jpg-1-1536x864.jpeg 1536w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Gira-IIL.jpg-1-2048x1153.jpeg 2048w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Gira-IIL.jpg-1-600x338.jpeg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>No \u00e2mbito do Latam Mobility &amp; Net Zero Brasil 2026, o CEO do Canal Solar, Bernardo Marang\u00f3n, apresentou a palestra intitulada &#8220;Quando a energia solar encontra o asfalto&#8221; . Durante sua fala, o especialista do setor el\u00e9trico brasileiro tra\u00e7ou um paralelo entre o crescimento explosivo da energia solar fotovoltaica no Brasil e o potencial igualmente&#8230;<\/p>\n","protected":false},"author":10,"featured_media":64853,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[2972],"tags":[2253,2347,2360,3704,3593],"class_list":["post-64866","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-encuentros-movilidad-sostenible-pt-br","tag-brasil","tag-brasil-3","tag-brasil-pt-br","tag-canal-solar","tag-latam-mobility-brasil-2026"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Canal Solar aposta no armazenamento BESS como solu\u00e7\u00e3o para recarga de ve\u00edculos - Latam Mobility<\/title>\n<meta name=\"description\" content=\"No \u00e2mbito do Latam Mobility &amp; Net Zero Brasil 2026, o CEO do Canal Solar, Bernardo Marang\u00f3n, apresentou a palestra intitulada &quot;Quando a energia solar\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/latamobility.com\/pt-br\/canal-solar-aposta-no-armazenamento-bes-como-solucao-para-recarga-de-veiculos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Canal Solar aposta no armazenamento BESS como solu\u00e7\u00e3o para recarga de ve\u00edculos\" \/>\n<meta property=\"og:description\" content=\"No \u00e2mbito do Latam Mobility &amp; Net Zero Brasil 2026, o CEO do Canal Solar, Bernardo Marang\u00f3n, apresentou a palestra intitulada &quot;Quando a energia solar\" \/>\n<meta property=\"og:url\" content=\"https:\/\/latamobility.com\/pt-br\/canal-solar-aposta-no-armazenamento-bes-como-solucao-para-recarga-de-veiculos\/\" \/>\n<meta property=\"og:site_name\" content=\"Latam Mobility\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/latamobility\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-08T10:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T15:15:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/05\/Canal-Solar-a.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Antonio Vilela\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LataMobility\" \/>\n<meta name=\"twitter:site\" content=\"@LataMobility\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Antonio Vilela\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/latamobility.com\\\/pt-br\\\/canal-solar-aposta-no-armazenamento-bes-como-solucao-para-recarga-de-veiculos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/latamobility.com\\\/pt-br\\\/canal-solar-aposta-no-armazenamento-bes-como-solucao-para-recarga-de-veiculos\\\/\"},\"author\":{\"name\":\"Antonio Vilela\",\"@id\":\"https:\\\/\\\/latamobility.com\\\/#\\\/schema\\\/person\\\/fda092a2de1f87d347784282908bad1a\"},\"headline\":\"Canal Solar aposta no armazenamento BESS como solu\u00e7\u00e3o para recarga de ve\u00edculos\",\"datePublished\":\"2026-05-08T10:00:00+00:00\",\"dateModified\":\"2026-05-08T15:15:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/latamobility.com\\\/pt-br\\\/canal-solar-aposta-no-armazenamento-bes-como-solucao-para-recarga-de-veiculos\\\/\"},\"wordCount\":1378,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/latamobility.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/latamobility.com\\\/pt-br\\\/canal-solar-aposta-no-armazenamento-bes-como-solucao-para-recarga-de-veiculos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/latamobility.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Canal-Solar-a.jpg\",\"keywords\":[\"Brasil\",\"Brasil\",\"Brasil\",\"Canal Solar\",\"Latam Mobility Brasil 2026\"],\"articleSection\":[\"Encuentros\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/latamobility.com\\\/pt-br\\\/canal-solar-aposta-no-armazenamento-bes-como-solucao-para-recarga-de-veiculos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/latamobility.com\\\/pt-br\\\/canal-solar-aposta-no-armazenamento-bes-como-solucao-para-recarga-de-veiculos\\\/\",\"url\":\"https:\\\/\\\/latamobility.com\\\/pt-br\\\/canal-solar-aposta-no-armazenamento-bes-como-solucao-para-recarga-de-veiculos\\\/\",\"name\":\"Canal Solar aposta no armazenamento BESS como solu\u00e7\u00e3o para recarga de ve\u00edculos - Latam Mobility\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/latamobility.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/latamobility.com\\\/pt-br\\\/canal-solar-aposta-no-armazenamento-bes-como-solucao-para-recarga-de-veiculos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/latamobility.com\\\/pt-br\\\/canal-solar-aposta-no-armazenamento-bes-como-solucao-para-recarga-de-veiculos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/latamobility.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Canal-Solar-a.jpg\",\"datePublished\":\"2026-05-08T10:00:00+00:00\",\"dateModified\":\"2026-05-08T15:15:01+00:00\",\"description\":\"No \u00e2mbito do Latam Mobility &amp; Net Zero Brasil 2026, o CEO do Canal Solar, Bernardo Marang\u00f3n, apresentou a palestra intitulada \\\"Quando a energia solar\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/latamobility.com\\\/pt-br\\\/canal-solar-aposta-no-armazenamento-bes-como-solucao-para-recarga-de-veiculos\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/latamobility.com\\\/pt-br\\\/canal-solar-aposta-no-armazenamento-bes-como-solucao-para-recarga-de-veiculos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/latamobility.com\\\/pt-br\\\/canal-solar-aposta-no-armazenamento-bes-como-solucao-para-recarga-de-veiculos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/latamobility.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Canal-Solar-a.jpg\",\"contentUrl\":\"https:\\\/\\\/latamobility.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Canal-Solar-a.jpg\",\"width\":2048,\"height\":1365,\"caption\":\"Canal Solar\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/latamobility.com\\\/pt-br\\\/canal-solar-aposta-no-armazenamento-bes-como-solucao-para-recarga-de-veiculos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/latamobility.com\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Canal Solar aposta no armazenamento BESS como solu\u00e7\u00e3o para recarga de ve\u00edculos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/latamobility.com\\\/#website\",\"url\":\"https:\\\/\\\/latamobility.com\\\/\",\"name\":\"Latam Mobility\",\"description\":\"Serie de Eventos para promover la Movilidad y Transporte sostenible en Latinoam\u00e9rica\",\"publisher\":{\"@id\":\"https:\\\/\\\/latamobility.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/latamobility.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/latamobility.com\\\/#organization\",\"name\":\"LATAM MOBILITY\",\"url\":\"https:\\\/\\\/latamobility.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/latamobility.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/latamobility.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/logos-LM-LG-2025-10.png\",\"contentUrl\":\"https:\\\/\\\/latamobility.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/logos-LM-LG-2025-10.png\",\"width\":1080,\"height\":1080,\"caption\":\"LATAM MOBILITY\"},\"image\":{\"@id\":\"https:\\\/\\\/latamobility.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/latamobility\\\/\",\"https:\\\/\\\/x.com\\\/LataMobility\",\"https:\\\/\\\/www.instagram.com\\\/latamobility\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/latamobility\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCtcslRCRY0vITWaOQ1X0XUA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/latamobility.com\\\/#\\\/schema\\\/person\\\/fda092a2de1f87d347784282908bad1a\",\"name\":\"Antonio Vilela\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7eee8196fd2fda180806d7b41cd517f274d5ad3b9f65d873feb3ca7e2b3a72d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7eee8196fd2fda180806d7b41cd517f274d5ad3b9f65d873feb3ca7e2b3a72d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7eee8196fd2fda180806d7b41cd517f274d5ad3b9f65d873feb3ca7e2b3a72d2?s=96&d=mm&r=g\",\"caption\":\"Antonio Vilela\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Canal Solar aposta no armazenamento BESS como solu\u00e7\u00e3o para recarga de ve\u00edculos - Latam Mobility","description":"No \u00e2mbito do Latam Mobility &amp; Net Zero Brasil 2026, o CEO do Canal Solar, Bernardo Marang\u00f3n, apresentou a palestra intitulada \"Quando a energia solar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/latamobility.com\/pt-br\/canal-solar-aposta-no-armazenamento-bes-como-solucao-para-recarga-de-veiculos\/","og_locale":"pt_BR","og_type":"article","og_title":"Canal Solar aposta no armazenamento BESS como solu\u00e7\u00e3o para recarga de ve\u00edculos","og_description":"No \u00e2mbito do Latam Mobility &amp; Net Zero Brasil 2026, o CEO do Canal Solar, Bernardo Marang\u00f3n, apresentou a palestra intitulada \"Quando a energia solar","og_url":"https:\/\/latamobility.com\/pt-br\/canal-solar-aposta-no-armazenamento-bes-como-solucao-para-recarga-de-veiculos\/","og_site_name":"Latam Mobility","article_publisher":"https:\/\/www.facebook.com\/latamobility\/","article_published_time":"2026-05-08T10:00:00+00:00","article_modified_time":"2026-05-08T15:15:01+00:00","og_image":[{"width":2048,"height":1365,"url":"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/05\/Canal-Solar-a.jpg","type":"image\/jpeg"}],"author":"Antonio Vilela","twitter_card":"summary_large_image","twitter_creator":"@LataMobility","twitter_site":"@LataMobility","twitter_misc":{"Escrito por":"Antonio Vilela","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/latamobility.com\/pt-br\/canal-solar-aposta-no-armazenamento-bes-como-solucao-para-recarga-de-veiculos\/#article","isPartOf":{"@id":"https:\/\/latamobility.com\/pt-br\/canal-solar-aposta-no-armazenamento-bes-como-solucao-para-recarga-de-veiculos\/"},"author":{"name":"Antonio Vilela","@id":"https:\/\/latamobility.com\/#\/schema\/person\/fda092a2de1f87d347784282908bad1a"},"headline":"Canal Solar aposta no armazenamento BESS como solu\u00e7\u00e3o para recarga de ve\u00edculos","datePublished":"2026-05-08T10:00:00+00:00","dateModified":"2026-05-08T15:15:01+00:00","mainEntityOfPage":{"@id":"https:\/\/latamobility.com\/pt-br\/canal-solar-aposta-no-armazenamento-bes-como-solucao-para-recarga-de-veiculos\/"},"wordCount":1378,"commentCount":0,"publisher":{"@id":"https:\/\/latamobility.com\/#organization"},"image":{"@id":"https:\/\/latamobility.com\/pt-br\/canal-solar-aposta-no-armazenamento-bes-como-solucao-para-recarga-de-veiculos\/#primaryimage"},"thumbnailUrl":"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/05\/Canal-Solar-a.jpg","keywords":["Brasil","Brasil","Brasil","Canal Solar","Latam Mobility Brasil 2026"],"articleSection":["Encuentros"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/latamobility.com\/pt-br\/canal-solar-aposta-no-armazenamento-bes-como-solucao-para-recarga-de-veiculos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/latamobility.com\/pt-br\/canal-solar-aposta-no-armazenamento-bes-como-solucao-para-recarga-de-veiculos\/","url":"https:\/\/latamobility.com\/pt-br\/canal-solar-aposta-no-armazenamento-bes-como-solucao-para-recarga-de-veiculos\/","name":"Canal Solar aposta no armazenamento BESS como solu\u00e7\u00e3o para recarga de ve\u00edculos - Latam Mobility","isPartOf":{"@id":"https:\/\/latamobility.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/latamobility.com\/pt-br\/canal-solar-aposta-no-armazenamento-bes-como-solucao-para-recarga-de-veiculos\/#primaryimage"},"image":{"@id":"https:\/\/latamobility.com\/pt-br\/canal-solar-aposta-no-armazenamento-bes-como-solucao-para-recarga-de-veiculos\/#primaryimage"},"thumbnailUrl":"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/05\/Canal-Solar-a.jpg","datePublished":"2026-05-08T10:00:00+00:00","dateModified":"2026-05-08T15:15:01+00:00","description":"No \u00e2mbito do Latam Mobility &amp; Net Zero Brasil 2026, o CEO do Canal Solar, Bernardo Marang\u00f3n, apresentou a palestra intitulada \"Quando a energia solar","breadcrumb":{"@id":"https:\/\/latamobility.com\/pt-br\/canal-solar-aposta-no-armazenamento-bes-como-solucao-para-recarga-de-veiculos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/latamobility.com\/pt-br\/canal-solar-aposta-no-armazenamento-bes-como-solucao-para-recarga-de-veiculos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/latamobility.com\/pt-br\/canal-solar-aposta-no-armazenamento-bes-como-solucao-para-recarga-de-veiculos\/#primaryimage","url":"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/05\/Canal-Solar-a.jpg","contentUrl":"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/05\/Canal-Solar-a.jpg","width":2048,"height":1365,"caption":"Canal Solar"},{"@type":"BreadcrumbList","@id":"https:\/\/latamobility.com\/pt-br\/canal-solar-aposta-no-armazenamento-bes-como-solucao-para-recarga-de-veiculos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/latamobility.com\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Canal Solar aposta no armazenamento BESS como solu\u00e7\u00e3o para recarga de ve\u00edculos"}]},{"@type":"WebSite","@id":"https:\/\/latamobility.com\/#website","url":"https:\/\/latamobility.com\/","name":"Latam Mobility","description":"Serie de Eventos para promover la Movilidad y Transporte sostenible en Latinoam\u00e9rica","publisher":{"@id":"https:\/\/latamobility.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/latamobility.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/latamobility.com\/#organization","name":"LATAM MOBILITY","url":"https:\/\/latamobility.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/latamobility.com\/#\/schema\/logo\/image\/","url":"https:\/\/latamobility.com\/wp-content\/uploads\/2025\/01\/logos-LM-LG-2025-10.png","contentUrl":"https:\/\/latamobility.com\/wp-content\/uploads\/2025\/01\/logos-LM-LG-2025-10.png","width":1080,"height":1080,"caption":"LATAM MOBILITY"},"image":{"@id":"https:\/\/latamobility.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/latamobility\/","https:\/\/x.com\/LataMobility","https:\/\/www.instagram.com\/latamobility\/","https:\/\/www.linkedin.com\/company\/latamobility\/","https:\/\/www.youtube.com\/channel\/UCtcslRCRY0vITWaOQ1X0XUA"]},{"@type":"Person","@id":"https:\/\/latamobility.com\/#\/schema\/person\/fda092a2de1f87d347784282908bad1a","name":"Antonio Vilela","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/7eee8196fd2fda180806d7b41cd517f274d5ad3b9f65d873feb3ca7e2b3a72d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7eee8196fd2fda180806d7b41cd517f274d5ad3b9f65d873feb3ca7e2b3a72d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7eee8196fd2fda180806d7b41cd517f274d5ad3b9f65d873feb3ca7e2b3a72d2?s=96&d=mm&r=g","caption":"Antonio Vilela"}}]}},"_links":{"self":[{"href":"https:\/\/latamobility.com\/pt-br\/wp-json\/wp\/v2\/posts\/64866","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/latamobility.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latamobility.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latamobility.com\/pt-br\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/latamobility.com\/pt-br\/wp-json\/wp\/v2\/comments?post=64866"}],"version-history":[{"count":4,"href":"https:\/\/latamobility.com\/pt-br\/wp-json\/wp\/v2\/posts\/64866\/revisions"}],"predecessor-version":[{"id":65074,"href":"https:\/\/latamobility.com\/pt-br\/wp-json\/wp\/v2\/posts\/64866\/revisions\/65074"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latamobility.com\/pt-br\/wp-json\/wp\/v2\/media\/64853"}],"wp:attachment":[{"href":"https:\/\/latamobility.com\/pt-br\/wp-json\/wp\/v2\/media?parent=64866"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latamobility.com\/pt-br\/wp-json\/wp\/v2\/categories?post=64866"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latamobility.com\/pt-br\/wp-json\/wp\/v2\/tags?post=64866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}