{"id":67656,"date":"2026-06-24T05:00:00","date_gmt":"2026-06-24T10:00:00","guid":{"rendered":"https:\/\/latamobility.com\/?p=67656"},"modified":"2026-06-22T09:50:32","modified_gmt":"2026-06-22T14:50:32","slug":"jet-desembarca-na-cidade-do-mexico-com-seu-servico-de-micromobilidade-e-reforca-operacao-na-copa-do-mundo","status":"publish","type":"post","link":"https:\/\/latamobility.com\/pt-br\/jet-desembarca-na-cidade-do-mexico-com-seu-servico-de-micromobilidade-e-reforca-operacao-na-copa-do-mundo\/","title":{"rendered":"JET Desembarca na Cidade do M\u00e9xico com seu Servi\u00e7o de Micromobilidade e Refor\u00e7a Opera\u00e7\u00e3o na Copa do Mundo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Em um movimento que redefine a mobilidade urbana em uma das metr\u00f3poles mais populosas do mundo, a empresa de micromobilidade <strong>JET<\/strong> anunciou oficialmente o in\u00edcio de suas opera\u00e7\u00f5es na Cidade do M\u00e9xico, a maior capital da Am\u00e9rica Latina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O servi\u00e7o de patinetes el\u00e9tricos chega para se consolidar como uma alternativa \u00e1gil, acess\u00edvel e sustent\u00e1vel para os milh\u00f5es de moradores e visitantes que percorrem diariamente as ruas dessa vibrante cidade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como parte desse lan\u00e7amento \u2014 e da estrat\u00e9gia de apoio a grandes eventos \u2014 a empresa tamb\u00e9m montou uma opera\u00e7\u00e3o especial com <strong>500 patinetes adicionais<\/strong> ao redor do Est\u00e1dio Azteca para facilitar o acesso dos torcedores aos jogos da Copa do Mundo de 2026.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com essa dupla a\u00e7\u00e3o, a <strong>JET<\/strong> n\u00e3o s\u00f3 entra no mercado mais din\u00e2mico da regi\u00e3o, mas tamb\u00e9m mostra sua capacidade de se adaptar a contextos de alta demanda, <strong>posicionando-se como um aliado estrat\u00e9gico para a mobilidade de \u00faltima milha<\/strong> em situa\u00e7\u00f5es extraordin\u00e1rias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Voc\u00ea tamb\u00e9m pode se interessar por | <a href=\"https:\/\/latamobility.com\/pt-br\/latam-mobility-tour-2026-encerra-passagem-por-medellin-e-segue-para-santiago-e-cidade-do-mexico\/\">&#8220;Latam Mobility Tour 2026&#8221; Encerra Passagem por Medell\u00edn e Segue para Santiago do Chile e Cidade do M\u00e9xico<\/a><\/strong><\/p>\n\n\n\n<h2 id=\"h-compromisso-integral-com-a-ultima-milha-e-a-sustentabilidade-urbana\" class=\"wp-block-heading\"><strong>Compromisso Integral com a \u00daltima Milha e a Sustentabilidade Urbana<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Agora, circular pela Cidade do M\u00e9xico tem uma nova op\u00e7\u00e3o. O servi\u00e7o da <strong>JET<\/strong> vai complementar o sistema de transporte de uma das maiores megal\u00f3poles do mundo, oferecendo deslocamentos confort\u00e1veis de \u00faltima milha para moradores e visitantes, conectando esta\u00e7\u00f5es de metr\u00f4, terminais de integra\u00e7\u00e3o e pontos de \u00f4nibus aos destinos finais dos usu\u00e1rios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A <strong>JET<\/strong> enxerga suas solu\u00e7\u00f5es como um complemento importante ao transporte p\u00fablico, facilitando trajetos curtos que <strong>economizam tempo, reduzem o tr\u00e2nsito e diminuem a depend\u00eancia do carro<\/strong> \u2014 contribuindo para uma mobilidade urbana mais \u00e1gil, pr\u00e1tica e sustent\u00e1vel na capital mexicana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A empresa refor\u00e7a que seus patinetes el\u00e9tricos s\u00e3o projetados para percursos com dura\u00e7\u00e3o m\u00e9dia de 10 a 15 minutos, faixa que cobre a maioria dos deslocamentos de \u00faltima milha em \u00e1reas densamente povoadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No in\u00edcio do m\u00eas, a <strong>JET<\/strong> j\u00e1 realizou projetos-piloto de apoio \u00e0 mobilidade urbana durante partidas da Liga MX. Organizados em parceria com atores locais, os testes tiveram resposta positiva da popula\u00e7\u00e3o, que usou ativamente o servi\u00e7o para trajetos curtos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/06\/JET-220626-c.jpg\" alt=\"JET\" class=\"wp-image-67643\" srcset=\"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/06\/JET-220626-c.jpg 1024w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/06\/JET-220626-c-300x169.jpg 300w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/06\/JET-220626-c-768x432.jpg 768w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/06\/JET-220626-c-600x338.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Durante os pilotos nos dias 3 e 9 de maio, <strong>os usu\u00e1rios fizeram mais de 500 viagens em apenas dois dias<\/strong>, confirmando a alta demanda por solu\u00e7\u00f5es de micromobilidade durante grandes eventos esportivos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Essa resposta favor\u00e1vel abriu caminho para a implanta\u00e7\u00e3o definitiva do servi\u00e7o na capital e, ao mesmo tempo, forneceu \u00e0 empresa dados valiosos sobre padr\u00f5es de uso, pontos de maior fluxo e necessidades log\u00edsticas \u2014 insights que agora s\u00e3o aplicados tanto na opera\u00e7\u00e3o regular quanto na opera\u00e7\u00e3o especial da Copa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A experi\u00eancia adquirida nesses pilotos foi essencial para que a <strong>JET<\/strong> pudesse oferecer um servi\u00e7o confi\u00e1vel e ajustado \u00e0s exig\u00eancias de uma cidade t\u00e3o complexa quanto a Cidade do M\u00e9xico.<\/p>\n\n\n\n<h2 id=\"h-implantacao-progressiva-em-zonas-estrategicas\" class=\"wp-block-heading\"><strong>Implanta\u00e7\u00e3o Progressiva em Zonas Estrat\u00e9gicas<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">No \u00e2mbito do per\u00edodo piloto atual, a empresa vai implantar gradualmente os primeiros <strong>1.000 patinetes el\u00e9tricos<\/strong> na cidade, em linha com a autoriza\u00e7\u00e3o inicial para opera\u00e7\u00e3o do servi\u00e7o e com planos de expans\u00e3o futura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A cobertura inicial abrange zonas estrat\u00e9gicas com alta demanda de mobilidade urbana: Cuauht\u00e9moc, Benito Ju\u00e1rez, Miguel Hidalgo e outras regi\u00f5es da zona metropolitana, conectando pontos-chave para moradores, trabalhadores e visitantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Essa sele\u00e7\u00e3o de regi\u00f5es \u00e9 fruto de uma an\u00e1lise detalhada dos fluxos de transporte, densidade populacional e presen\u00e7a de n\u00f3s de integra\u00e7\u00e3o, como esta\u00e7\u00f5es de metr\u00f4, pontos de \u00f4nibus e terminais de transfer\u00eancia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A <strong>JET<\/strong> prev\u00ea que, \u00e0 medida que o servi\u00e7o se consolidar e a aceita\u00e7\u00e3o crescer, a frota e a cobertura ser\u00e3o ampliadas para outras regi\u00f5es, levando a micromobilidade a mais cantos da megal\u00f3pole.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, a empresa ser\u00e1 uma das parceiras de transporte da Copa do Mundo. A ampla \u00e1rea de cobertura do servi\u00e7o e a extensa rede de zonas de estacionamento v\u00e3o permitir que moradores e visitantes se desloquem confortavelmente entre terminais de transporte, est\u00e1dios, zonas de torcedores e outros pontos importantes do torneio.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"67643\" src=\"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/06\/JET-220626-c.jpg\" alt=\"JET\" class=\"wp-image-67643\" srcset=\"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/06\/JET-220626-c.jpg 1024w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/06\/JET-220626-c-300x169.jpg 300w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/06\/JET-220626-c-768x432.jpg 768w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/06\/JET-220626-c-600x338.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"381\" height=\"678\" data-id=\"67646\" src=\"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/06\/JET-220626-d.jpg\" alt=\"JET\" class=\"wp-image-67646\" srcset=\"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/06\/JET-220626-d.jpg 381w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/06\/JET-220626-d-169x300.jpg 169w\" sizes=\"(max-width: 381px) 100vw, 381px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Os usu\u00e1rios tamb\u00e9m ter\u00e3o acesso a estacionamentos localizados pr\u00f3ximos \u00e0 infraestrutura esportiva, <strong>transformando a micromobilidade em um aliado estrat\u00e9gico para a log\u00edstica do evento<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A <strong>JET<\/strong> coordenou com as autoridades locais para garantir que os pontos de estacionamento e as rotas sugeridas sejam compat\u00edveis com os per\u00edmetros de seguran\u00e7a e os bloqueios vi\u00e1rios previstos, assegurando que os torcedores possam aproveitar o servi\u00e7o sem interferir nos dispositivos de controle estabelecidos.<\/p>\n\n\n\n<h2 id=\"h-tecnologia-seguranca-e-regras-de-uso\" class=\"wp-block-heading\"><strong>Tecnologia, Seguran\u00e7a e Regras de Uso<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Os patinetes el\u00e9tricos da <strong>JET<\/strong> contam com sistema de freios, luz traseira, placa de identifica\u00e7\u00e3o, monitoramento por GPS e velocidade m\u00e1xima de <strong>20 km\/h<\/strong> , em conformidade com a regulamenta\u00e7\u00e3o vigente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como parte do compromisso com a seguran\u00e7a dos usu\u00e1rios, a empresa implementa monitoramento cont\u00ednuo da frota e oferece seguro para o usu\u00e1rio durante o uso do ve\u00edculo. O servi\u00e7o \u00e9 solicitado pelo aplicativo GO JET, dispon\u00edvel para iOS e Android, onde os usu\u00e1rios podem localizar, desbloquear e finalizar suas viagens de forma r\u00e1pida e simples.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A plataforma foi desenvolvida para oferecer uma experi\u00eancia simples, acess\u00edvel e alinhada com a proposta de micromobilidade da empresa. O aplicativo tamb\u00e9m inclui um mapa interativo que mostra os pontos de estacionamento autorizados, o status da bateria de cada unidade e o tempo estimado de viagem, permitindo que os usu\u00e1rios planejem seus deslocamentos com anteced\u00eancia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre as principais regras de uso est\u00e3o: a loca\u00e7\u00e3o e o uso de patinetes el\u00e9tricos \u00e9 proibido para menores de 18 anos; os patinetes <strong>JET<\/strong> s\u00e3o ve\u00edculos de uso individual e n\u00e3o \u00e9 permitido circular em dupla; n\u00e3o \u00e9 permitido o uso para transporte de carga ou servi\u00e7os de entrega; o ve\u00edculo deve ser estacionado apenas nos pontos indicados no mapa do aplicativo; e o ve\u00edculo nunca deve ser abandonado na via p\u00fablica, sobre cal\u00e7adas, em frente a faixas de pedestres, acessos de ve\u00edculos ou rampas de acessibilidade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Essas medidas buscam garantir uma conviv\u00eancia harmoniosa entre os usu\u00e1rios de micromobilidade e os demais atores do tr\u00e2nsito<\/strong>, al\u00e9m de preservar o espa\u00e7o p\u00fablico e a acessibilidade para pessoas com defici\u00eancia. A <strong>JET<\/strong> implementou um sistema de verifica\u00e7\u00e3o de idade e um processo de registro que exige identifica\u00e7\u00e3o oficial para garantir o cumprimento das regras.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">&#8220;A Cidade do M\u00e9xico \u00e9 um dos mercados mais din\u00e2micos e importantes da Am\u00e9rica Latina, com milh\u00f5es de pessoas que se deslocam diariamente em busca de alternativas de transporte mais eficientes. <strong>Chegar \u00e0 capital \u00e9 um momento-chave para a JET:<\/strong> nos permite nos aproximar de uma comunidade diversa, ativa e com enorme potencial para adotar a micromobilidade como parte da vida urbana.&#8221;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2014 <strong>V\u00edctor Coelho<\/strong>, gerente de Rela\u00e7\u00f5es P\u00fablicas LATAM da JET<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Para a <strong>JET<\/strong>, esta \u00e9 uma alian\u00e7a estrat\u00e9gica importante voltada para o desenvolvimento da mobilidade urbana e para o aumento da acessibilidade do transporte para moradores e visitantes. A empresa espera que essa colabora\u00e7\u00e3o se estenda a futuras fases de expans\u00e3o e \u00e0 implementa\u00e7\u00e3o de melhorias tecnol\u00f3gicas, como a integra\u00e7\u00e3o com sistemas de pagamento p\u00fablicos e a amplia\u00e7\u00e3o da frota para cobrir novas \u00e1reas da cidade.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/06\/JET-220626-e.jpg\" alt=\"JET\" class=\"wp-image-67649\" srcset=\"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/06\/JET-220626-e.jpg 1024w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/06\/JET-220626-e-300x169.jpg 300w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/06\/JET-220626-e-768x432.jpg 768w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/06\/JET-220626-e-600x338.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Um 2026 de consolida\u00e7\u00e3o para a mobilidade<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O <strong>Tour Latam Mobility 2026<\/strong> chegar\u00e1 a <strong><a href=\"https:\/\/latamobility.com\/pt-br\/summit\/latam-mobility-conosur-2026\/\">Santiago, no Chile, no dia 25 de agosto<\/a><\/strong>, reunindo especialistas e atores estrat\u00e9gicos para continuar fortalecendo o ecossistema de mobilidade sustent\u00e1vel na regi\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O evento terminar\u00e1 na <strong><a href=\"https:\/\/latamobility.com\/pt-br\/summit\/latam-mobility-mexico-2026\/\">Cidade do M\u00e9xico nos dias 12 e 13 de outubro<\/a><\/strong>, juntamente com o <strong>Climate Economy Forum<\/strong>, em um encontro que reunir\u00e1 l\u00edderes do setor para continuar impulsionando a transi\u00e7\u00e3o para sistemas de transporte mais eficientes, sustent\u00e1veis e de baixas emiss\u00f5es na Am\u00e9rica Latina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>A transi\u00e7\u00e3o j\u00e1 est\u00e1 em curso.<\/strong> O <strong>Tour 2026 do Latam Mobility<\/strong> ser\u00e1 o ponto de encontro para acelerar decis\u00f5es, conectar atores\u2011chave e construir, de forma colaborativa, a <strong>mobilidade sustent\u00e1vel da Am\u00e9rica Latina.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Gira-IIL.jpg-1-1024x576.jpeg\" alt=\"\" class=\"wp-image-63893\" srcset=\"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Gira-IIL.jpg-1-1024x576.jpeg 1024w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Gira-IIL.jpg-1-300x169.jpeg 300w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Gira-IIL.jpg-1-768x432.jpeg 768w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Gira-IIL.jpg-1-1536x864.jpeg 1536w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Gira-IIL.jpg-1-2048x1153.jpeg 2048w, https:\/\/latamobility.com\/wp-content\/uploads\/2026\/04\/Gira-IIL.jpg-1-600x338.jpeg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Em um movimento que redefine a mobilidade urbana em uma das metr\u00f3poles mais populosas do mundo, a empresa de micromobilidade JET anunciou oficialmente o in\u00edcio de suas opera\u00e7\u00f5es na Cidade do M\u00e9xico, a maior capital da Am\u00e9rica Latina. O servi\u00e7o de patinetes el\u00e9tricos chega para se consolidar como uma alternativa \u00e1gil, acess\u00edvel e sustent\u00e1vel para&#8230;<\/p>\n","protected":false},"author":10,"featured_media":67640,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[2356],"tags":[3333,3356,3370],"class_list":["post-67656","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-movilidad-electrica-pt-br","tag-jet-2","tag-mexico-pt-br","tag-micromovilidad-pt-br"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>JET Desembarca na Cidade do M\u00e9xico com seu Servi\u00e7o de Micromobilidade e Refor\u00e7a Opera\u00e7\u00e3o na Copa do Mundo - Latam Mobility<\/title>\n<meta name=\"description\" content=\"Em um movimento que redefine a mobilidade urbana em uma das metr\u00f3poles mais populosas do mundo, a empresa de micromobilidade JET anunciou oficialmente o\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/latamobility.com\/?p=67632\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"JET Desembarca na Cidade do M\u00e9xico com seu Servi\u00e7o de Micromobilidade e Refor\u00e7a Opera\u00e7\u00e3o na Copa do Mundo\" \/>\n<meta property=\"og:description\" content=\"Em um movimento que redefine a mobilidade urbana em uma das metr\u00f3poles mais populosas do mundo, a empresa de micromobilidade JET anunciou oficialmente o\" \/>\n<meta property=\"og:url\" content=\"https:\/\/latamobility.com\/?p=67632\" \/>\n<meta property=\"og:site_name\" content=\"Latam Mobility\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/latamobility\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-24T10:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/06\/JET-220626-b.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Antonio Vilela\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LataMobility\" \/>\n<meta name=\"twitter:site\" content=\"@LataMobility\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Antonio Vilela\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/latamobility.com\\\/?p=67632#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/latamobility.com\\\/?p=67632\"},\"author\":{\"name\":\"Antonio Vilela\",\"@id\":\"https:\\\/\\\/latamobility.com\\\/#\\\/schema\\\/person\\\/fda092a2de1f87d347784282908bad1a\"},\"headline\":\"JET Desembarca na Cidade do M\u00e9xico com seu Servi\u00e7o de Micromobilidade e Refor\u00e7a Opera\u00e7\u00e3o na Copa do Mundo\",\"datePublished\":\"2026-06-24T10:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/latamobility.com\\\/?p=67632\"},\"wordCount\":1432,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/latamobility.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/latamobility.com\\\/?p=67632#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/latamobility.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/JET-220626-b.jpg\",\"keywords\":[\"JET\",\"M\u00e9xico\",\"micromovilidad\"],\"articleSection\":[\"Movilidad el\u00e9ctrica\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/latamobility.com\\\/?p=67632#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/latamobility.com\\\/?p=67632\",\"url\":\"https:\\\/\\\/latamobility.com\\\/?p=67632\",\"name\":\"JET Desembarca na Cidade do M\u00e9xico com seu Servi\u00e7o de Micromobilidade e Refor\u00e7a Opera\u00e7\u00e3o na Copa do Mundo - Latam Mobility\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/latamobility.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/latamobility.com\\\/?p=67632#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/latamobility.com\\\/?p=67632#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/latamobility.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/JET-220626-b.jpg\",\"datePublished\":\"2026-06-24T10:00:00+00:00\",\"description\":\"Em um movimento que redefine a mobilidade urbana em uma das metr\u00f3poles mais populosas do mundo, a empresa de micromobilidade JET anunciou oficialmente o\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/latamobility.com\\\/?p=67632#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/latamobility.com\\\/?p=67632\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/latamobility.com\\\/?p=67632#primaryimage\",\"url\":\"https:\\\/\\\/latamobility.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/JET-220626-b.jpg\",\"contentUrl\":\"https:\\\/\\\/latamobility.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/JET-220626-b.jpg\",\"width\":1024,\"height\":576,\"caption\":\"JET\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/latamobility.com\\\/?p=67632#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/latamobility.com\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"JET Desembarca na Cidade do M\u00e9xico com seu Servi\u00e7o de Micromobilidade e Refor\u00e7a Opera\u00e7\u00e3o na Copa do Mundo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/latamobility.com\\\/#website\",\"url\":\"https:\\\/\\\/latamobility.com\\\/\",\"name\":\"Latam Mobility\",\"description\":\"Serie de Eventos para promover la Movilidad y Transporte sostenible en Latinoam\u00e9rica\",\"publisher\":{\"@id\":\"https:\\\/\\\/latamobility.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/latamobility.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/latamobility.com\\\/#organization\",\"name\":\"LATAM MOBILITY\",\"url\":\"https:\\\/\\\/latamobility.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/latamobility.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/latamobility.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/logos-LM-LG-2025-10.png\",\"contentUrl\":\"https:\\\/\\\/latamobility.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/logos-LM-LG-2025-10.png\",\"width\":1080,\"height\":1080,\"caption\":\"LATAM MOBILITY\"},\"image\":{\"@id\":\"https:\\\/\\\/latamobility.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/latamobility\\\/\",\"https:\\\/\\\/x.com\\\/LataMobility\",\"https:\\\/\\\/www.instagram.com\\\/latamobility\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/latamobility\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCtcslRCRY0vITWaOQ1X0XUA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/latamobility.com\\\/#\\\/schema\\\/person\\\/fda092a2de1f87d347784282908bad1a\",\"name\":\"Antonio Vilela\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7eee8196fd2fda180806d7b41cd517f274d5ad3b9f65d873feb3ca7e2b3a72d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7eee8196fd2fda180806d7b41cd517f274d5ad3b9f65d873feb3ca7e2b3a72d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7eee8196fd2fda180806d7b41cd517f274d5ad3b9f65d873feb3ca7e2b3a72d2?s=96&d=mm&r=g\",\"caption\":\"Antonio Vilela\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"JET Desembarca na Cidade do M\u00e9xico com seu Servi\u00e7o de Micromobilidade e Refor\u00e7a Opera\u00e7\u00e3o na Copa do Mundo - Latam Mobility","description":"Em um movimento que redefine a mobilidade urbana em uma das metr\u00f3poles mais populosas do mundo, a empresa de micromobilidade JET anunciou oficialmente o","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/latamobility.com\/?p=67632","og_locale":"pt_BR","og_type":"article","og_title":"JET Desembarca na Cidade do M\u00e9xico com seu Servi\u00e7o de Micromobilidade e Refor\u00e7a Opera\u00e7\u00e3o na Copa do Mundo","og_description":"Em um movimento que redefine a mobilidade urbana em uma das metr\u00f3poles mais populosas do mundo, a empresa de micromobilidade JET anunciou oficialmente o","og_url":"https:\/\/latamobility.com\/?p=67632","og_site_name":"Latam Mobility","article_publisher":"https:\/\/www.facebook.com\/latamobility\/","article_published_time":"2026-06-24T10:00:00+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/06\/JET-220626-b.jpg","type":"image\/jpeg"}],"author":"Antonio Vilela","twitter_card":"summary_large_image","twitter_creator":"@LataMobility","twitter_site":"@LataMobility","twitter_misc":{"Escrito por":"Antonio Vilela","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/latamobility.com\/?p=67632#article","isPartOf":{"@id":"https:\/\/latamobility.com\/?p=67632"},"author":{"name":"Antonio Vilela","@id":"https:\/\/latamobility.com\/#\/schema\/person\/fda092a2de1f87d347784282908bad1a"},"headline":"JET Desembarca na Cidade do M\u00e9xico com seu Servi\u00e7o de Micromobilidade e Refor\u00e7a Opera\u00e7\u00e3o na Copa do Mundo","datePublished":"2026-06-24T10:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/latamobility.com\/?p=67632"},"wordCount":1432,"commentCount":0,"publisher":{"@id":"https:\/\/latamobility.com\/#organization"},"image":{"@id":"https:\/\/latamobility.com\/?p=67632#primaryimage"},"thumbnailUrl":"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/06\/JET-220626-b.jpg","keywords":["JET","M\u00e9xico","micromovilidad"],"articleSection":["Movilidad el\u00e9ctrica"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/latamobility.com\/?p=67632#respond"]}]},{"@type":"WebPage","@id":"https:\/\/latamobility.com\/?p=67632","url":"https:\/\/latamobility.com\/?p=67632","name":"JET Desembarca na Cidade do M\u00e9xico com seu Servi\u00e7o de Micromobilidade e Refor\u00e7a Opera\u00e7\u00e3o na Copa do Mundo - Latam Mobility","isPartOf":{"@id":"https:\/\/latamobility.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/latamobility.com\/?p=67632#primaryimage"},"image":{"@id":"https:\/\/latamobility.com\/?p=67632#primaryimage"},"thumbnailUrl":"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/06\/JET-220626-b.jpg","datePublished":"2026-06-24T10:00:00+00:00","description":"Em um movimento que redefine a mobilidade urbana em uma das metr\u00f3poles mais populosas do mundo, a empresa de micromobilidade JET anunciou oficialmente o","breadcrumb":{"@id":"https:\/\/latamobility.com\/?p=67632#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/latamobility.com\/?p=67632"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/latamobility.com\/?p=67632#primaryimage","url":"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/06\/JET-220626-b.jpg","contentUrl":"https:\/\/latamobility.com\/wp-content\/uploads\/2026\/06\/JET-220626-b.jpg","width":1024,"height":576,"caption":"JET"},{"@type":"BreadcrumbList","@id":"https:\/\/latamobility.com\/?p=67632#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/latamobility.com\/pt-br\/"},{"@type":"ListItem","position":2,"name":"JET Desembarca na Cidade do M\u00e9xico com seu Servi\u00e7o de Micromobilidade e Refor\u00e7a Opera\u00e7\u00e3o na Copa do Mundo"}]},{"@type":"WebSite","@id":"https:\/\/latamobility.com\/#website","url":"https:\/\/latamobility.com\/","name":"Latam Mobility","description":"Serie de Eventos para promover la Movilidad y Transporte sostenible en Latinoam\u00e9rica","publisher":{"@id":"https:\/\/latamobility.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/latamobility.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/latamobility.com\/#organization","name":"LATAM MOBILITY","url":"https:\/\/latamobility.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/latamobility.com\/#\/schema\/logo\/image\/","url":"https:\/\/latamobility.com\/wp-content\/uploads\/2025\/01\/logos-LM-LG-2025-10.png","contentUrl":"https:\/\/latamobility.com\/wp-content\/uploads\/2025\/01\/logos-LM-LG-2025-10.png","width":1080,"height":1080,"caption":"LATAM MOBILITY"},"image":{"@id":"https:\/\/latamobility.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/latamobility\/","https:\/\/x.com\/LataMobility","https:\/\/www.instagram.com\/latamobility\/","https:\/\/www.linkedin.com\/company\/latamobility\/","https:\/\/www.youtube.com\/channel\/UCtcslRCRY0vITWaOQ1X0XUA"]},{"@type":"Person","@id":"https:\/\/latamobility.com\/#\/schema\/person\/fda092a2de1f87d347784282908bad1a","name":"Antonio Vilela","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/7eee8196fd2fda180806d7b41cd517f274d5ad3b9f65d873feb3ca7e2b3a72d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7eee8196fd2fda180806d7b41cd517f274d5ad3b9f65d873feb3ca7e2b3a72d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7eee8196fd2fda180806d7b41cd517f274d5ad3b9f65d873feb3ca7e2b3a72d2?s=96&d=mm&r=g","caption":"Antonio Vilela"}}]}},"_links":{"self":[{"href":"https:\/\/latamobility.com\/pt-br\/wp-json\/wp\/v2\/posts\/67656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/latamobility.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latamobility.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latamobility.com\/pt-br\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/latamobility.com\/pt-br\/wp-json\/wp\/v2\/comments?post=67656"}],"version-history":[{"count":1,"href":"https:\/\/latamobility.com\/pt-br\/wp-json\/wp\/v2\/posts\/67656\/revisions"}],"predecessor-version":[{"id":67657,"href":"https:\/\/latamobility.com\/pt-br\/wp-json\/wp\/v2\/posts\/67656\/revisions\/67657"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latamobility.com\/pt-br\/wp-json\/wp\/v2\/media\/67640"}],"wp:attachment":[{"href":"https:\/\/latamobility.com\/pt-br\/wp-json\/wp\/v2\/media?parent=67656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latamobility.com\/pt-br\/wp-json\/wp\/v2\/categories?post=67656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latamobility.com\/pt-br\/wp-json\/wp\/v2\/tags?post=67656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}